{"id":1950,"date":"2026-02-24T15:27:21","date_gmt":"2026-02-24T14:27:21","guid":{"rendered":"https:\/\/smulakademin.com\/academic-year-calendar\/"},"modified":"2026-05-04T16:01:40","modified_gmt":"2026-05-04T14:01:40","slug":"academic-year-calendar","status":"publish","type":"page","link":"https:\/\/smulakademin.com\/en\/academic-year-calendar\/","title":{"rendered":"Academic Year Calendar"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section preset--module--divi-section--default\">\n<div class=\"et_pb_row_0 et_pb_row et_pb_gutters1 et_block_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--default\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><h1>Academic Year Calendar 2026\/2027<\/h1>\n<\/div><\/div>\n\n<div class=\"dvmd_table_maker_0 dvmd_table_maker dvmd_tm_version_4_0_1 et_pb_module\"><div className=\"et_pb_module_inner\"><div\n        role=\"table\"\n        class=\"dvmd_tm_table \"\n        \n        \n        aria-rowcount=\"43\"\n        aria-colcount=\"3\"\n      >\n        <div class=\"dvmd_tm_trow dvmd_tm_trow_0\" role=\"row\" aria-rowindex=\"1\"><div aria-colindex=\"1\" aria-rowindex=\"1\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_0 dvmd_tm_col_first dvmd_tm_row_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\"><b>Vecka<\/b><\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"1\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_0 dvmd_tm_row_first dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\"><b>Datum<\/b><\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"1\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_0 dvmd_tm_col_last dvmd_tm_row_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\"><b>Aktivitet<\/b><\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_1\" role=\"row\" aria-rowindex=\"2\"><div aria-colindex=\"1\" aria-rowindex=\"2\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_1 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">35<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"2\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_1 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">30\/8<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"2\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_1 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">F&ouml;r&auml;ldram&ouml;ten, se aktuellt datum p&aring; respektive kurssida<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_2\" role=\"row\" aria-rowindex=\"3\"><div aria-colindex=\"1\" aria-rowindex=\"3\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_2 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">36<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"3\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_2 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">1\/9<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"3\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_2 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Sista dagen att betala fakturan \/Instruktioner om undervisningen skickas ut.<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_3\" role=\"row\" aria-rowindex=\"4\"><div aria-colindex=\"1\" aria-rowindex=\"4\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_3 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">37<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"4\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_3 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">7-13\/9<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"4\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_3 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 1<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_4\" role=\"row\" aria-rowindex=\"5\"><div aria-colindex=\"1\" aria-rowindex=\"5\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_4 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">38<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"5\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_4 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">14-20\/9<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"5\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_4 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 2<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_5\" role=\"row\" aria-rowindex=\"6\"><div aria-colindex=\"1\" aria-rowindex=\"6\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_5 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">39<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"6\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_5 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">21-27\/9<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"6\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_5 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 3<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_6\" role=\"row\" aria-rowindex=\"7\"><div aria-colindex=\"1\" aria-rowindex=\"7\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_6 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">40<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"7\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_6 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">28\/9-4\/10<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"7\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_6 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 4<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_7\" role=\"row\" aria-rowindex=\"8\"><div aria-colindex=\"1\" aria-rowindex=\"8\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_7 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">41<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"8\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_7 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">5-11\/10<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"8\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_7 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">lektion 5<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_8\" role=\"row\" aria-rowindex=\"9\"><div aria-colindex=\"1\" aria-rowindex=\"9\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_8 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">42<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"9\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_8 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">12-18\/10<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"9\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_8 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 6<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_9\" role=\"row\" aria-rowindex=\"10\"><div aria-colindex=\"1\" aria-rowindex=\"10\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_9 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">43<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"10\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_9 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">19-25\/10<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"10\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_9 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">H&ouml;stlov, vecka 1 (Sverige byter till vintertid 25\/10)<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_10\" role=\"row\" aria-rowindex=\"11\"><div aria-colindex=\"1\" aria-rowindex=\"11\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_10 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">44<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"11\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_10 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">26\/10-1\/11<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"11\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_10 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">H&ouml;stlov, vecka 2 (USA och Kanada byter till vintertid1\/11)<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_11\" role=\"row\" aria-rowindex=\"12\"><div aria-colindex=\"1\" aria-rowindex=\"12\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_11 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">45<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"12\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_11 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">2-8\/11<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"12\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_11 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 7<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_12\" role=\"row\" aria-rowindex=\"13\"><div aria-colindex=\"1\" aria-rowindex=\"13\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_12 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">46<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"13\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_12 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">9-15\/11<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"13\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_12 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 8<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_13\" role=\"row\" aria-rowindex=\"14\"><div aria-colindex=\"1\" aria-rowindex=\"14\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_13 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">47<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"14\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_13 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">16-22\/11<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"14\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_13 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 9<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_14\" role=\"row\" aria-rowindex=\"15\"><div aria-colindex=\"1\" aria-rowindex=\"15\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_14 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">48<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"15\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_14 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">23-29\/11<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"15\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_14 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 10<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_15\" role=\"row\" aria-rowindex=\"16\"><div aria-colindex=\"1\" aria-rowindex=\"16\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_15 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">49<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"16\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_15 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">30\/11-6\/12<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"16\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_15 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 11<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_16\" role=\"row\" aria-rowindex=\"17\"><div aria-colindex=\"1\" aria-rowindex=\"17\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_16 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">50<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"17\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_16 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">7-13\/12<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"17\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_16 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 12<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_17\" role=\"row\" aria-rowindex=\"18\"><div aria-colindex=\"1\" aria-rowindex=\"18\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_17 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\"><\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"18\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_17 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">13\/12<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"18\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_17 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Luciafriande p&aring; Zoom, kl 18.00 svensk tid<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_18\" role=\"row\" aria-rowindex=\"19\"><div aria-colindex=\"1\" aria-rowindex=\"19\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_18 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">51-1<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"19\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_18 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">14\/12-10\/1<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"19\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_18 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Jullov<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_19\" role=\"row\" aria-rowindex=\"20\"><div aria-colindex=\"1\" aria-rowindex=\"20\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_19 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">2<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"20\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_19 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">11-17\/1<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"20\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_19 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 13<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_20\" role=\"row\" aria-rowindex=\"21\"><div aria-colindex=\"1\" aria-rowindex=\"21\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_20 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">3<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"21\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_20 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">18-24\/1<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"21\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_20 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 14<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_21\" role=\"row\" aria-rowindex=\"22\"><div aria-colindex=\"1\" aria-rowindex=\"22\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_21 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">4<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"22\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_21 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">25-31\/1<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"22\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_21 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 15<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_22\" role=\"row\" aria-rowindex=\"23\"><div aria-colindex=\"1\" aria-rowindex=\"23\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_22 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">5<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"23\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_22 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">1-7\/2<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"23\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_22 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 16<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_23\" role=\"row\" aria-rowindex=\"24\"><div aria-colindex=\"1\" aria-rowindex=\"24\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_23 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">6<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"24\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_23 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">8-14\/2<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"24\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_23 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 17<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_24\" role=\"row\" aria-rowindex=\"25\"><div aria-colindex=\"1\" aria-rowindex=\"25\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_24 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">7<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"25\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_24 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">12-21\/2<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"25\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_24 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 18<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_25\" role=\"row\" aria-rowindex=\"26\"><div aria-colindex=\"1\" aria-rowindex=\"26\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_25 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">8<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"26\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_25 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">22-28\/2<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"26\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_25 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 19<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_26\" role=\"row\" aria-rowindex=\"27\"><div aria-colindex=\"1\" aria-rowindex=\"27\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_26 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">9<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"27\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_26 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">1-7\/3<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"27\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_26 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">lektion 20<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_27\" role=\"row\" aria-rowindex=\"28\"><div aria-colindex=\"1\" aria-rowindex=\"28\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_27 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">10<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"28\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_27 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">8-14\/3<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"28\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_27 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 21 (USA och Kanada byter till sommartid 14\/3)<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_28\" role=\"row\" aria-rowindex=\"29\"><div aria-colindex=\"1\" aria-rowindex=\"29\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_28 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">11<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"29\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_28 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">15-21\/3<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"29\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_28 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">V&aring;rlov, vecka 1<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_29\" role=\"row\" aria-rowindex=\"30\"><div aria-colindex=\"1\" aria-rowindex=\"30\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_29 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">12<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"30\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_29 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">22-28\/3<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"30\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_29 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">V&aring;rlov , vecka 2 (Sverige byter till sommartid 28\/3)<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_30\" role=\"row\" aria-rowindex=\"31\"><div aria-colindex=\"1\" aria-rowindex=\"31\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_30 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">13<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"31\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_30 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">29\/3-4\/4<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"31\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_30 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 22<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_31\" role=\"row\" aria-rowindex=\"32\"><div aria-colindex=\"1\" aria-rowindex=\"32\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_31 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\"><\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"32\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_31 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">4\/4<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"32\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_31 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">P&aring;skpyssel via zoom, kl 18.00 svensk tid<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_32\" role=\"row\" aria-rowindex=\"33\"><div aria-colindex=\"1\" aria-rowindex=\"33\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_32 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">14<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"33\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_32 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">5-11\/4<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"33\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_32 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 23<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_33\" role=\"row\" aria-rowindex=\"34\"><div aria-colindex=\"1\" aria-rowindex=\"34\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_33 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">15<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"34\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_33 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">12-18\/4<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"34\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_33 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 24<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_34\" role=\"row\" aria-rowindex=\"35\"><div aria-colindex=\"1\" aria-rowindex=\"35\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_34 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">16<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"35\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_34 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">19-25\/4<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"35\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_34 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 25<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_35\" role=\"row\" aria-rowindex=\"36\"><div aria-colindex=\"1\" aria-rowindex=\"36\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_35 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">17<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"36\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_35 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">26\/4-2\/5<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"36\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_35 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 26<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_36\" role=\"row\" aria-rowindex=\"37\"><div aria-colindex=\"1\" aria-rowindex=\"37\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_36 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">18<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"37\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_36 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">3-9\/5<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"37\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_36 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 27<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_37\" role=\"row\" aria-rowindex=\"38\"><div aria-colindex=\"1\" aria-rowindex=\"38\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_37 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">19<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"38\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_37 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">10-16\/5<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"38\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_37 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 28<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_38\" role=\"row\" aria-rowindex=\"39\"><div aria-colindex=\"1\" aria-rowindex=\"39\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_38 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">20<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"39\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_38 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">17-23\/5<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"39\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_38 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Lektion 29<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_39\" role=\"row\" aria-rowindex=\"40\"><div aria-colindex=\"1\" aria-rowindex=\"40\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_39 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">21<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"40\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_39 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">24-30\/5<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"40\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_39 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Lektion 30<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_40\" role=\"row\" aria-rowindex=\"41\"><div aria-colindex=\"1\" aria-rowindex=\"41\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_40 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">22<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"41\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_40 dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">31\/5-6\/6<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"41\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_40 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Redovisning<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_41\" role=\"row\" aria-rowindex=\"42\"><div aria-colindex=\"1\" aria-rowindex=\"42\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_41 dvmd_tm_col_first dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">23<\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"42\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_41 dvmd_tm_col_even dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">7-13\/6<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"42\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_41 dvmd_tm_col_last dvmd_tm_col_odd dvmd_tm_row_even \"><div class=\"dvmd_tm_cdata\">Redovisning<\/div><\/div>\n<\/div><div class=\"dvmd_tm_trow dvmd_tm_trow_42\" role=\"row\" aria-rowindex=\"43\"><div aria-colindex=\"1\" aria-rowindex=\"43\" role=\"cell\" class=\"dvmd_table_maker_item_0 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_0 dvmd_tm_row_42 dvmd_tm_col_first dvmd_tm_row_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\"><\/div><\/div>\n<div aria-colindex=\"2\" aria-rowindex=\"43\" role=\"cell\" class=\"dvmd_table_maker_item_1 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_1 dvmd_tm_row_42 dvmd_tm_row_last dvmd_tm_col_even dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">13\/6<\/div><\/div>\n<div aria-colindex=\"3\" aria-rowindex=\"43\" role=\"cell\" class=\"dvmd_table_maker_item_2 dvmd_tm_tcell dvmd_tm_tdata dvmd_tm_col_2 dvmd_tm_row_42 dvmd_tm_col_last dvmd_tm_row_last dvmd_tm_col_odd dvmd_tm_row_odd \"><div class=\"dvmd_tm_cdata\">Skolavslutning p&aring; zoom, kl 18.00 svensk tid<\/div><\/div>\n<\/div>\n      <\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1950","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/smulakademin.com\/en\/wp-json\/wp\/v2\/pages\/1950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smulakademin.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/smulakademin.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/smulakademin.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smulakademin.com\/en\/wp-json\/wp\/v2\/comments?post=1950"}],"version-history":[{"count":2,"href":"https:\/\/smulakademin.com\/en\/wp-json\/wp\/v2\/pages\/1950\/revisions"}],"predecessor-version":[{"id":1955,"href":"https:\/\/smulakademin.com\/en\/wp-json\/wp\/v2\/pages\/1950\/revisions\/1955"}],"wp:attachment":[{"href":"https:\/\/smulakademin.com\/en\/wp-json\/wp\/v2\/media?parent=1950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}